{"id":925,"date":"2013-04-02T15:31:26","date_gmt":"2013-04-02T13:31:26","guid":{"rendered":"https:\/\/mafra.it\/blog\/?p=925"},"modified":"2025-02-20T12:45:34","modified_gmt":"2025-02-20T11:45:34","slug":"il-nuovo-profumatore-ma-fra-hippy-il-fiore-happy","status":"publish","type":"post","link":"https:\/\/mafra.it\/blog\/il-nuovo-profumatore-ma-fra-hippy-il-fiore-happy\/","title":{"rendered":"Il nuovo profumatore MA-FRA: Hippy&#8230; Il Fiore Happy"},"content":{"rendered":"<p><a href=\"https:\/\/mafra.it\/blog\/il-nuovo-profumatore-ma-fra-hippy-il-fiore-happy\/pagweb-hippy-7\/\" rel=\"attachment wp-att-926\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-926\" alt=\"pagweb-hippy-7\" src=\"https:\/\/mafra.it\/blog\/wp-content\/uploads\/2013\/04\/pagweb-hippy-7.jpg\" width=\"640\" height=\"486\" \/><\/a><\/p>\n<p>Hippy \u00e8 il nuovo profumatore MA-FRA realizzato per regalarti un sorriso ogni volta che entrerai nell\u2019abitacolo della tua auto. In ogni viaggio sarai avvolto nell&#8217;atmosfera di un tempo che non c&#8217;\u00e8 pi\u00f9. Il nome Hippy abbraccia i valori di una generazione che ha cambiato il mondo, ripensando i suoi valori in una nuova realt\u00e0: Flower Power, Imagine Peace, Love Freedom, Nature Trip, Heaven\u2019s Door e Summer Of Love possono ancora cambiare il Mondo!<\/p>\n<p>Hippy \u00e8 la Margherita in gomma profumata di MA-FRA realizzata con materiali di ultima generazione e studiata per essere inserita con semplicit\u00e0 nella bocchetta di aerazione: sicura e garantita da tutta la qualit\u00e0 Made in Italy di MA-FRA.<\/p>\n<p>La speciale gomma utilizzata, resistente sia alle alte temperature che alla stagione invernale, \u00e8 brevetto esclusivo italiano, come sono completamente Made in Italy le 6 fragranze dedicate a ogni margherita.<\/p>\n<p>Hippy non \u00e8 quindi il solito profumatore, ma qualcosa di totalmente diverso: uno stimolo a recuperare i propri sogni, un piccolo oggetto destinato a diventare un&#8217;icona glamour da collezione. Vi baster\u00e0 cos\u00ec un semplice respiro per essere immersi nel sogno di una nuova primavera.<\/p>\n<p>Regala un fiore alla tua auto: regalati un sogno che rinasce ogni primavera!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hippy \u00e8 il nuovo profumatore MA-FRA realizzato per regalarti un sorriso ogni volta che entrerai nell\u2019abitacolo della tua auto. In ogni viaggio sarai avvolto nell&#8217;atmosfera di un tempo che non c&#8217;\u00e8 pi\u00f9. Il nome Hippy abbraccia i valori di una generazione che ha cambiato il mondo, ripensando i suoi valori in una nuova realt\u00e0: Flower [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":930,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1401,1371],"tags":[1343],"class_list":["post-925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-profumatori","category-pulizia-interni","tag-auto"],"modified_by":"MafraBlog","_links":{"self":[{"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/posts\/925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/comments?post=925"}],"version-history":[{"count":1,"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/posts\/925\/revisions"}],"predecessor-version":[{"id":12106,"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/posts\/925\/revisions\/12106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/media\/930"}],"wp:attachment":[{"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/media?parent=925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/categories?post=925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/tags?post=925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}