{"id":8610,"date":"2021-05-17T18:00:36","date_gmt":"2021-05-17T16:00:36","guid":{"rendered":"https:\/\/mafra.it\/blog\/?p=8610"},"modified":"2025-02-20T15:32:14","modified_gmt":"2025-02-20T14:32:14","slug":"vanni-oddera-campione-di-motocross-freestyle-e-mototerapia","status":"publish","type":"post","link":"https:\/\/mafra.it\/blog\/vanni-oddera-campione-di-motocross-freestyle-e-mototerapia\/","title":{"rendered":"Vanni Oddera, campione di motocross freestyle e Mototerapia"},"content":{"rendered":"<h1><strong>Vanni Oddera, campione di motocross freestyle e Mototerapia<\/strong><\/h1>\n<h4><strong>Vanni Oddera da anni porta avanti un progetto molto importante: la Mototerapia. Grazie al suo impegno, il noto campione italiano di Motocross Freestyle porta un sorriso ai bambini che ne hanno pi\u00f9 bisogno, quelli con gravi disabilit\u00e0 e malattie oncologiche. Noi siamo orgogliosi di essere al suo fianco in questa attivit\u00e0 e vogliamo raccontarvi la sua storia.<\/strong><\/h4>\n<p>I motori sono la nostra passione\u2026 e <strong>quando una passione \u00e8 condivisa<\/strong> si moltiplica, diventando ancora pi\u00f9 forte. Oggi vogliamo raccontarti una storia di vera passione e condivisione. Il protagonista \u00e8 <strong>Vanni Oddera<\/strong>, campione mondiale di <strong>motocross freestyle<\/strong>, un atleta che supportiamo ormai da tempo e farlo ci riempie di orgoglio. Nato nel 1980 a Pontivrea (Savona), la sua storia \u00e8 tutta da leggere, puoi scoprirla <strong><a href=\"https:\/\/www.vannioddera.it\/my-story\/\" target=\"_blank\" rel=\"noopener noreferrer\">qui<\/a><\/strong>.<\/p>\n<h3><strong>La Mototerapia di Vanni Oddera: piacere adrenalinico e gioia da condividere<\/strong><\/h3>\n<p>Vanni Oddera non \u00e8 solo il protagonista di <strong>spericolate evoluzioni<\/strong> <strong>mozzafiato<\/strong> in sella alla sua moto\u2026 \u00e8 anche e soprattutto <strong>uno dei migliori interpreti al mondo<\/strong> di questa disciplina. Ormai da diversi anni, Vanni Oddera porta in tutto il mondo la <strong>gioia e l\u2019emozione di vivere un giro in moto<\/strong>. Una libert\u00e0 troppo bella ma non sempre accessibile a tutti.<img decoding=\"async\" class=\"aligncenter size-medium wp-image-8635\" src=\"https:\/\/mafra.it\/blog\/wp-content\/uploads\/2021\/05\/vanni-oddera-alba4-300x200.jpeg\" alt=\"Vanni Oddera\" width=\"300\" height=\"200\"\/><\/p>\n<h5 style=\"text-align: center;\"><strong>Se si salta da soli \u00e8 solo un salto<\/strong><\/h5>\n<h5 style=\"text-align: center;\"><strong>se si salta insieme \u00e8 la vita che inizia davvero\u2026 <\/strong><\/h5>\n<p>Il progetto di&nbsp;<a href=\"https:\/\/www.vannioddera.it\/mototerapiaco\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Mototerapia<\/strong><\/a> di Vanni Oddera \u00e8 nato nel 2008 ed \u00e8 dedicato a bambini che hanno bisogni speciali.&nbsp;Per Vanni Oddera, il progetto consiste nel condividere con loro la sua <strong>passione<\/strong>, la moto. &nbsp;Grazie alla &#8220;Mototerapia&#8221;, i bambini possono provare l&#8217;emozione di salire in sella a una moto, per una giornata ricca di adrenalina e divertimento. Con tantissime sessioni nel corso dell\u2019anno, Vanni Oddera regala <strong>un\u2019esperienza unica<\/strong> ai bambini speciali a cavallo della sua moto.<a href=\"https:\/\/www.vannioddera.it\/mototerapiaco\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter wp-image-8639 size-medium\" src=\"https:\/\/mafra.it\/blog\/wp-content\/uploads\/2021\/05\/vanni-oddera__8_-300x188.jpg\" alt=\"Vanni Oddera Mototerapia\" width=\"300\" height=\"188\"\/><\/a><\/p>\n<p>Il pubblico pu\u00f2 assistere a <strong>esibizioni di motocross acrobatica<\/strong> ma, soprattutto, bambini disabili, portatori di handicap, malati oncologici e persone in carrozzina possono provare l&#8217;euforia di salire, con lui, in sella a una moto. E pi\u00f9 di una volta, Vanni Oddera ha raccontato la gioia nel vedere le loro reazioni, paragonandole a quelle di uno dei pi\u00f9 emozionanti film fantasy che conosciamo. &#8220;Rimangono estasiati, scivolano sull\u2019aria. Credo che la sensazione sia quella che prova Atreiu, il protagonista de <em><strong>La storia infinita<\/strong><\/em> quando sale sul drago, lo prende per le orecchie e vola&#8221;.<\/p>\n<h3><strong>La forza della condivisione<\/strong><\/h3>\n<p>Vanni Oddera condivide il progetto di Mototerapia con i&nbsp;<strong>24 piloti<\/strong>&nbsp;<strong>italiani<\/strong> del suo <strong>team di motocross freestyle<\/strong>,&nbsp;<a href=\"https:\/\/daboot.it\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Daboot<\/strong><\/a>. Un Team che promuove ormai dal 2002 il freestyle motocross con esibizioni, gare ed eventi, in tutta Italia, Europa e nel mondo.<a href=\"https:\/\/daboot.it\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter wp-image-8645 size-large\" src=\"https:\/\/mafra.it\/blog\/wp-content\/uploads\/2021\/05\/Daboot-1024x614.jpg\" alt=\"Vanni Oddera - Daboot\" width=\"640\" height=\"384\"\/><\/a><\/p>\n<p>Tutti i piloti hanno compreso perfettamente e abbracciato questo progetto speciale che \u00e8 la <strong>Mototerapia<\/strong>. Vanni li ha&nbsp;<strong>coinvolti tutti<\/strong>, e proprio il condividere questa attivit\u00e0 ha trasformato profondamente anche i loro rapporti, facendoli diventare pi\u00f9 che una squadra, un <strong>gruppo di amici.<\/strong><\/p>\n<h5 style=\"text-align: center;\"><strong>Fare del bene fa bene!<\/strong><\/h5>\n<h3><strong>Un progetto che arriva anche in corsia<\/strong><\/h3>\n<p>E, se i ragazzi non possono andare a godersi lo spettacolo di freestyle, ecco che Vanni Oddera e il suo Team portano lo spettacolo in ospedale, naturalmente in moto (elettrica), con il progetto&nbsp;<a href=\"https:\/\/www.vannioddera.it\/2020\/01\/23\/freestyle-hospital-5809\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Freestyle Hospital<\/strong><\/a>. Dal 2014, il nostro campione porta in tutta Italia questa attivit\u00e0, che prevede di <strong>percorrere le corsie degli ospedali<\/strong>, portando sulla sella della moto i bambini ricoverati. Un progetto al quale teniamo particolarmente perch\u00e9 permette ai piccoli di svagarsi, riportando il sorriso sui loro volti.<\/p>\n<p><a href=\"https:\/\/www.vannioddera.it\/2020\/01\/23\/freestyle-hospital-5809\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter wp-image-8671 size-full\" src=\"https:\/\/mafra.it\/blog\/wp-content\/uploads\/2021\/05\/186094551_10159844035680190_4910063656286621975_n.jpg\" alt=\"\" width=\"960\" height=\"640\"\/><\/a><\/p>\n<p>Un motivo in pi\u00f9 per sostenerlo: nel marzo 2020, uno studio <strong>dell\u2019Ospedale Regina Margherita di Torino<\/strong>, riconosce ufficialmente i benefici della <strong>Mototerapia<\/strong> sui pazienti oncologici.<\/p>\n<h3><strong>La Mototerapia in tempi di COVID-19 <\/strong><\/h3>\n<p>Neanche la pandemia ha fermato l\u2019attivit\u00e0 di&nbsp;<strong>Vanni Oddera <\/strong>e del<strong> suo Team<\/strong>. Insieme ad un gruppo di amici, il campione ha creato il protocollo per la&nbsp;<strong>Mototerapia Take-away<\/strong>, per portare la sua moto direttamente a casa delle persone.<\/p>\n<h3><strong>Passione infinita<\/strong><\/h3>\n<p>Fin da bambino, il sogno di Vanni Oddera era possedere una moto e con i primi soldi guadagnati ne ha comprata una. E in sella alla sua moto la sua vita \u00e8 cambiata. Vanni Oddera \u00e8 diventato campione di freestyle motocross. I suoi gioielli a due ruote, con i quali <strong>porta il sorriso in giro per il mondo<\/strong>, sono un vero spettacolo. Goditeli tutti <a href=\"https:\/\/www.vannioddera.it\/category\/moto\/\" target=\"_blank\" rel=\"noopener\">qui<\/a>.<\/p>\n<p><a href=\"https:\/\/www.ponteallegrazie.it\/libro\/il-grande-salto-vanni-oddera-9788868336752.html\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignleft wp-image-8641 size-full\" src=\"https:\/\/mafra.it\/blog\/wp-content\/uploads\/2021\/05\/Libro-Vanni-Oddera.jpg\" alt=\"Vanni Oddera - Il Grande Salto\" width=\"185\" height=\"273\"\/><\/a><\/p>\n<h5 style=\"text-align: center;\"><strong>L\u2019amore per gli altri rende felici<\/strong><\/h5>\n<p>Vanni Oddera ci racconta la sua vita, il \u201csuo salto\u201d, in un libro autobiografico: <a href=\"https:\/\/www.ponteallegrazie.it\/libro\/il-grande-salto-vanni-oddera-9788868336752.html\" target=\"_blank\" rel=\"noopener noreferrer\"><em>\u201cIl grande salto. Come ho capito che l\u2019amore per gli altri rende felici\u201d<\/em><\/a><em>,<\/em> edito da Ponte alle Grazie.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: center;\"><strong>Grande Vanni, noi siamo sempre pi\u00f9 fieri di te e ci godiamo i tuoi spettacoli!!!<\/strong><\/h4>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=314&amp;href=https%3A%2F%2Fwww.facebook.com%2F60242070189%2Fvideos%2F10156499789515190%2F&amp;show_text=false&amp;width=560\" width=\"560\" height=\"314\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Segui tutte le imprese di Vanni sui suoi canali social: <strong><a href=\"https:\/\/www.facebook.com\/Vanni-Oddera-60242070189\/?fref=ts\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a><\/strong>, <a href=\"https:\/\/www.instagram.com\/vannioddera\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Instagram<\/strong><\/a>, <strong><a href=\"https:\/\/www.youtube.com\/channel\/UCgCSWB4fTxcOUC1yleYkR4g\" target=\"_blank\" rel=\"noopener noreferrer\">Youtube<\/a><\/strong><\/p>\n<p>[foogallery id=&#8221;8650&#8243;]<\/p>\n<h4>Continua a seguirci sui <strong>nostri canali social<\/strong> per tanti altri <strong>consigli utili sulla cura dell\u2019auto:<\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.auto-spa.it\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignleft wp-image-4864\" title=\"Web\" src=\"https:\/\/mafra.it\/blog\/wp-content\/uploads\/2018\/11\/web-2.png\" sizes=\"(max-width: 40px) 100vw, 40px\" srcset=\"https:\/\/mafra.it\/blog\/wp-content\/uploads\/2018\/11\/web-2.png 152w, https:\/\/mafra.it\/blog\/wp-content\/uploads\/2018\/11\/web-2-150x150.png 150w\" alt=\"\" width=\"40\" height=\"40\"\/><\/a><a href=\"https:\/\/www.facebook.com\/MAFRA.ITALY\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignleft wp-image-4859\" title=\"Facebook\" src=\"https:\/\/mafra.it\/blog\/wp-content\/uploads\/2018\/11\/facebook.png\" alt=\"\" width=\"21\" height=\"40\"\/><\/a><\/p>\n<p><a href=\"https:\/\/www.instagram.com\/mafraofficial\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignleft wp-image-4860\" title=\"Instagram\" src=\"https:\/\/mafra.it\/blog\/wp-content\/uploads\/2018\/11\/instagram.png\" sizes=\"(max-width: 40px) 100vw, 40px\" srcset=\"https:\/\/mafra.it\/blog\/wp-content\/uploads\/2018\/11\/instagram.png 152w, https:\/\/mafra.it\/blog\/wp-content\/uploads\/2018\/11\/instagram-150x150.png 150w\" alt=\"\" width=\"40\" height=\"40\"\/><\/a><\/p>\n<p><a href=\"https:\/\/t.me\/mafrashop\"><img decoding=\"async\" class=\"alignleft wp-image-7961\" src=\"https:\/\/mafra.it\/blog\/wp-content\/uploads\/2021\/04\/icona-telegram-canale-mafra-shop-300x300.png\" alt=\"\" width=\"43\" height=\"42\"\/><\/a><a href=\"https:\/\/twitter.com\/mafra65\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignleft wp-image-4863\" title=\"Twitter\" src=\"https:\/\/mafra.it\/blog\/wp-content\/uploads\/2018\/11\/twitter-1.png\" alt=\"\" width=\"49\" height=\"40\"\/><\/a><a href=\"https:\/\/www.pinterest.it\/mafrapin\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignleft wp-image-4862\" title=\"Pinterest\" src=\"https:\/\/mafra.it\/blog\/wp-content\/uploads\/2018\/11\/pintarest.png\" alt=\"\" width=\"43\" height=\"40\"\/><\/a><a href=\"https:\/\/www.youtube.com\/user\/Mafraweb65\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone wp-image-4865\" title=\"You Tube\" src=\"https:\/\/mafra.it\/blog\/wp-content\/uploads\/2018\/11\/youtube-1-150x150.png\" alt=\"\" width=\"44\" height=\"40\"\/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vanni Oddera, campione di motocross freestyle e Mototerapia Vanni Oddera da anni porta avanti un progetto molto importante: la Mototerapia. Grazie al suo impegno, il noto campione italiano di Motocross Freestyle porta un sorriso ai bambini che ne hanno pi\u00f9 bisogno, quelli con gravi disabilit\u00e0 e malattie oncologiche. Noi siamo orgogliosi di essere al suo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8675,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1391],"tags":[1421],"class_list":["post-8610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-collaborazioni","tag-influecer"],"modified_by":"MafraBlog","_links":{"self":[{"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/posts\/8610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/comments?post=8610"}],"version-history":[{"count":1,"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/posts\/8610\/revisions"}],"predecessor-version":[{"id":14651,"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/posts\/8610\/revisions\/14651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/media\/8675"}],"wp:attachment":[{"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/media?parent=8610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/categories?post=8610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mafra.it\/blog\/wp-json\/wp\/v2\/tags?post=8610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}